{"id":8766,"date":"2024-08-21T12:00:00","date_gmt":"2024-08-21T12:00:00","guid":{"rendered":"https:\/\/hogarortigosa.org\/?p=8766"},"modified":"2024-08-21T12:00:00","modified_gmt":"2024-08-21T12:00:00","slug":"capacitacion-en-proteccion-civil-siempre-preparados","status":"publish","type":"post","link":"https:\/\/hogarortigosa.org\/en\/capacitacion-en-proteccion-civil-siempre-preparados\/","title":{"rendered":"Capacitaci\u00f3n en Protecci\u00f3n Civil: Siempre Preparados"},"content":{"rendered":"<p>En Le\u00f3n Ortigosa ABP, la seguridad es una prioridad. Por ello, nuestro equipo particip\u00f3<br>en una jornada de capacitaci\u00f3n impartida por Protecci\u00f3n civil de nuevo Le\u00f3n, enfocada<br>en el manejo de emergencias relacionadas con fuego incipiente.<\/p>\n\n\n\n<p>Durante el curso, se abordaron temas fundamentales como los tipos de fuego, la<br>clasificaci\u00f3n y uso adecuado de extintores, medidas de prevenci\u00f3n tanto en el hogar<br>como en el lugar de trabajo, y las t\u00e9cnicas esenciales para combatir incendios<br>incipientes. Adem\u00e1s, se realizaron pr\u00e1cticas con extintores, reforzando la preparaci\u00f3n y<br>confianza de nuestro equipo ante posibles emergencias.<\/p>\n\n\n\n<p>Esta capacitaci\u00f3n refleja nuestro compromiso con la creaci\u00f3n de un entorno seguro y<br>con la promoci\u00f3n de una cultura preventiva. \u00a1Juntos, construimos un espacio protegido<br>para todos!<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"8768\" src=\"https:\/\/hogarortigosa.org\/wp-content\/uploads\/2025\/09\/IMG_3134-1024x576.jpeg\" alt=\"\" class=\"wp-image-8768\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"8767\" src=\"https:\/\/hogarortigosa.org\/wp-content\/uploads\/2025\/09\/IMG_3174-1024x768.jpeg\" alt=\"\" class=\"wp-image-8767\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"8770\" src=\"https:\/\/hogarortigosa.org\/wp-content\/uploads\/2025\/09\/IMG_3103-768x1024.jpeg\" alt=\"\" class=\"wp-image-8770\"\/><\/figure>\n<\/figure>\n\n\n\n<style>\n.byline {\n  display: none !important;\n}\n<\/style>","protected":false},"excerpt":{"rendered":"<p>En Le\u00f3n Ortigosa ABP, la seguridad es una prioridad. Por ello, nuestro equipo particip\u00f3en una jornada de capacitaci\u00f3n impartida por Protecci\u00f3n civil de nuevo Le\u00f3n, enfocadaen el manejo de emergencias relacionadas con fuego incipiente. Durante el curso, se abordaron temas fundamentales como los tipos de fuego, laclasificaci\u00f3n y uso adecuado de extintores, medidas de prevenci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8769,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[73],"tags":[],"class_list":["post-8766","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hogar-ortigosa"],"_links":{"self":[{"href":"https:\/\/hogarortigosa.org\/en\/wp-json\/wp\/v2\/posts\/8766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hogarortigosa.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hogarortigosa.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hogarortigosa.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hogarortigosa.org\/en\/wp-json\/wp\/v2\/comments?post=8766"}],"version-history":[{"count":0,"href":"https:\/\/hogarortigosa.org\/en\/wp-json\/wp\/v2\/posts\/8766\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hogarortigosa.org\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/hogarortigosa.org\/en\/wp-json\/wp\/v2\/media?parent=8766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hogarortigosa.org\/en\/wp-json\/wp\/v2\/categories?post=8766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hogarortigosa.org\/en\/wp-json\/wp\/v2\/tags?post=8766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}